{"id":2888,"date":"2022-10-05T15:51:29","date_gmt":"2022-10-05T20:51:29","guid":{"rendered":"https:\/\/www.flotalamacarena.com\/?p=2888"},"modified":"2024-11-18T11:37:18","modified_gmt":"2024-11-18T16:37:18","slug":"marce-la-recicladora","status":"publish","type":"post","link":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/","title":{"rendered":"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Sara Samaniego es Marce La Recicladora y ahora es su alter ego. <\/p>\n","protected":false},"author":3,"featured_media":2891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[37,43,38],"tags":[],"class_list":["post-2888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aventuras-macarena","category-blog","category-conociendo-a"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo. - Flota La Macarena S.A<\/title>\n<meta name=\"description\" content=\"\u00a1Conoce a Marce La Recicladora! La joven colombiana que est\u00e1 conquistando el mundo con su mensaje de reciclaje.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo. - Flota La Macarena S.A\" \/>\n<meta property=\"og:description\" content=\"\u00a1Conoce a Marce La Recicladora! La joven colombiana que est\u00e1 conquistando el mundo con su mensaje de reciclaje.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/\" \/>\n<meta property=\"og:site_name\" content=\"Flota La Macarena S.A\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/flota.lamacarenasa\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T20:51:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T16:37:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2023\/05\/recicladora.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1167\" \/>\n\t<meta property=\"og:image:height\" content=\"583\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Javier Prieto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FlotaLaMacarena\" \/>\n<meta name=\"twitter:site\" content=\"@FlotaLaMacarena\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Prieto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/\"},\"author\":{\"name\":\"Javier Prieto\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#\\\/schema\\\/person\\\/4c1a42f2560c0abd62779e7bd0868f33\"},\"headline\":\"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo.\",\"datePublished\":\"2022-10-05T20:51:29+00:00\",\"dateModified\":\"2024-11-18T16:37:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/\"},\"wordCount\":13,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/recicladora.jpg\",\"articleSection\":[\"Aventuras Macarena\",\"Blog\",\"Conociendo a\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/\",\"name\":\"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo. - Flota La Macarena S.A\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/recicladora.jpg\",\"datePublished\":\"2022-10-05T20:51:29+00:00\",\"dateModified\":\"2024-11-18T16:37:18+00:00\",\"description\":\"\u00a1Conoce a Marce La Recicladora! La joven colombiana que est\u00e1 conquistando el mundo con su mensaje de reciclaje.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/recicladora.jpg\",\"contentUrl\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/recicladora.jpg\",\"width\":1167,\"height\":583},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/marce-la-recicladora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/\",\"name\":\"Flota La Macarena S.A\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#organization\",\"name\":\"Flota La Macarena S.A\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/LOGO_FLM.png\",\"contentUrl\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/LOGO_FLM.png\",\"width\":450,\"height\":167,\"caption\":\"Flota La Macarena S.A\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/flota.lamacarenasa\\\/\",\"https:\\\/\\\/x.com\\\/FlotaLaMacarena\",\"https:\\\/\\\/www.youtube.com\\\/@flotalamacarena6335\",\"https:\\\/\\\/www.instagram.com\\\/flota_la_macarena\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/flota-la-macarena-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#\\\/schema\\\/person\\\/4c1a42f2560c0abd62779e7bd0868f33\",\"name\":\"Javier Prieto\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/author\\\/mastersite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo. - Flota La Macarena S.A","description":"\u00a1Conoce a Marce La Recicladora! La joven colombiana que est\u00e1 conquistando el mundo con su mensaje de reciclaje.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/","og_locale":"es_ES","og_type":"article","og_title":"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo. - Flota La Macarena S.A","og_description":"\u00a1Conoce a Marce La Recicladora! La joven colombiana que est\u00e1 conquistando el mundo con su mensaje de reciclaje.","og_url":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/","og_site_name":"Flota La Macarena S.A","article_publisher":"https:\/\/www.facebook.com\/flota.lamacarenasa\/","article_published_time":"2022-10-05T20:51:29+00:00","article_modified_time":"2024-11-18T16:37:18+00:00","og_image":[{"width":1167,"height":583,"url":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2023\/05\/recicladora.jpg","type":"image\/jpeg"}],"author":"Javier Prieto","twitter_card":"summary_large_image","twitter_creator":"@FlotaLaMacarena","twitter_site":"@FlotaLaMacarena","twitter_misc":{"Escrito por":"Javier Prieto","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#article","isPartOf":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/"},"author":{"name":"Javier Prieto","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#\/schema\/person\/4c1a42f2560c0abd62779e7bd0868f33"},"headline":"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo.","datePublished":"2022-10-05T20:51:29+00:00","dateModified":"2024-11-18T16:37:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/"},"wordCount":13,"commentCount":0,"publisher":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/#organization"},"image":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2023\/05\/recicladora.jpg","articleSection":["Aventuras Macarena","Blog","Conociendo a"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/","url":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/","name":"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo. - Flota La Macarena S.A","isPartOf":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#primaryimage"},"image":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2023\/05\/recicladora.jpg","datePublished":"2022-10-05T20:51:29+00:00","dateModified":"2024-11-18T16:37:18+00:00","description":"\u00a1Conoce a Marce La Recicladora! La joven colombiana que est\u00e1 conquistando el mundo con su mensaje de reciclaje.","breadcrumb":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#primaryimage","url":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2023\/05\/recicladora.jpg","contentUrl":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2023\/05\/recicladora.jpg","width":1167,"height":583},{"@type":"BreadcrumbList","@id":"https:\/\/www.flotalamacarena.com\/inicio\/marce-la-recicladora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.flotalamacarena.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Marce la recicladora, la influencer que busca generar conciencia para salvar el mundo."}]},{"@type":"WebSite","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#website","url":"https:\/\/www.flotalamacarena.com\/inicio\/","name":"Flota La Macarena S.A","description":"","publisher":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.flotalamacarena.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#organization","name":"Flota La Macarena S.A","url":"https:\/\/www.flotalamacarena.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2024\/03\/LOGO_FLM.png","contentUrl":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2024\/03\/LOGO_FLM.png","width":450,"height":167,"caption":"Flota La Macarena S.A"},"image":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/flota.lamacarenasa\/","https:\/\/x.com\/FlotaLaMacarena","https:\/\/www.youtube.com\/@flotalamacarena6335","https:\/\/www.instagram.com\/flota_la_macarena\/","https:\/\/www.linkedin.com\/company\/flota-la-macarena-s-a\/"]},{"@type":"Person","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#\/schema\/person\/4c1a42f2560c0abd62779e7bd0868f33","name":"Javier Prieto","url":"https:\/\/www.flotalamacarena.com\/inicio\/author\/mastersite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/posts\/2888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/comments?post=2888"}],"version-history":[{"count":3,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/posts\/2888\/revisions"}],"predecessor-version":[{"id":3463,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/posts\/2888\/revisions\/3463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/media\/2891"}],"wp:attachment":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/media?parent=2888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/categories?post=2888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/tags?post=2888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}