{"id":2740,"date":"2023-05-12T10:15:43","date_gmt":"2023-05-12T15:15:43","guid":{"rendered":"https:\/\/www.flotalamacarena.com\/?page_id=2740"},"modified":"2024-10-01T15:35:09","modified_gmt":"2024-10-01T15:35:09","slug":"siscore","status":"publish","type":"page","link":"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/","title":{"rendered":"siscore"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2740","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>siscore - Flota La Macarena S.A<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"siscore - Flota La Macarena S.A\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/\" \/>\n<meta property=\"og:site_name\" content=\"Flota La Macarena S.A\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/flota.lamacarenasa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T15:35:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FlotaLaMacarena\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/siscore\\\/\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/siscore\\\/\",\"name\":\"siscore - Flota La Macarena S.A\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#website\"},\"datePublished\":\"2023-05-12T15:15:43+00:00\",\"dateModified\":\"2024-10-01T15:35:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/siscore\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/siscore\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/siscore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"siscore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/\",\"name\":\"Flota La Macarena S.A\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#organization\",\"name\":\"Flota La Macarena S.A\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/LOGO_FLM.png\",\"contentUrl\":\"https:\\\/\\\/www.flotalamacarena.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/LOGO_FLM.png\",\"width\":450,\"height\":167,\"caption\":\"Flota La Macarena S.A\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flotalamacarena.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/flota.lamacarenasa\\\/\",\"https:\\\/\\\/x.com\\\/FlotaLaMacarena\",\"https:\\\/\\\/www.youtube.com\\\/@flotalamacarena6335\",\"https:\\\/\\\/www.instagram.com\\\/flota_la_macarena\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/flota-la-macarena-s-a\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"siscore - Flota La Macarena S.A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/","og_locale":"es_ES","og_type":"article","og_title":"siscore - Flota La Macarena S.A","og_url":"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/","og_site_name":"Flota La Macarena S.A","article_publisher":"https:\/\/www.facebook.com\/flota.lamacarenasa\/","article_modified_time":"2024-10-01T15:35:09+00:00","twitter_card":"summary_large_image","twitter_site":"@FlotaLaMacarena","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/","url":"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/","name":"siscore - Flota La Macarena S.A","isPartOf":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/#website"},"datePublished":"2023-05-12T15:15:43+00:00","dateModified":"2024-10-01T15:35:09+00:00","breadcrumb":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.flotalamacarena.com\/inicio\/siscore\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.flotalamacarena.com\/inicio\/siscore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.flotalamacarena.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"siscore"}]},{"@type":"WebSite","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#website","url":"https:\/\/www.flotalamacarena.com\/inicio\/","name":"Flota La Macarena S.A","description":"","publisher":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.flotalamacarena.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#organization","name":"Flota La Macarena S.A","url":"https:\/\/www.flotalamacarena.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.flotalamacarena.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2024\/03\/LOGO_FLM.png","contentUrl":"https:\/\/www.flotalamacarena.com\/wp-content\/uploads\/2024\/03\/LOGO_FLM.png","width":450,"height":167,"caption":"Flota La Macarena S.A"},"image":{"@id":"https:\/\/www.flotalamacarena.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/flota.lamacarenasa\/","https:\/\/x.com\/FlotaLaMacarena","https:\/\/www.youtube.com\/@flotalamacarena6335","https:\/\/www.instagram.com\/flota_la_macarena\/","https:\/\/www.linkedin.com\/company\/flota-la-macarena-s-a\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/pages\/2740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/comments?post=2740"}],"version-history":[{"count":1,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/pages\/2740\/revisions"}],"predecessor-version":[{"id":2741,"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/pages\/2740\/revisions\/2741"}],"wp:attachment":[{"href":"https:\/\/www.flotalamacarena.com\/inicio\/wp-json\/wp\/v2\/media?parent=2740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}